{"id":4539,"count":1,"description":"","link":"https:\/\/risawave.org\/de\/tag\/organisationswandel\/","name":"#Organisationswandel","slug":"organisationswandel","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>#Organisationswandel-Archiv - risawave.org<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/risawave.org\/de\/tag\/organisationswandel\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"#Organisationswandel-Archiv\" \/>\n<meta property=\"og:url\" content=\"https:\/\/risawave.org\/de\/tag\/organisationswandel\/\" \/>\n<meta property=\"og:site_name\" content=\"risawave.org\" \/>\n<meta property=\"og:image\" content=\"https:\/\/risawave.org\/wp-content\/uploads\/2026\/01\/Globales-logo-scaled-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/risawave.org\\\/de\\\/tag\\\/organisationswandel\\\/\",\"url\":\"https:\\\/\\\/risawave.org\\\/de\\\/tag\\\/organisationswandel\\\/\",\"name\":\"#Organisationswandel-Archiv - risawave.org\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/risawave.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/risawave.org\\\/de\\\/tag\\\/organisationswandel\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/risawave.org\\\/de\\\/tag\\\/organisationswandel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/risawave.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"#Organisationswandel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/risawave.org\\\/#website\",\"url\":\"https:\\\/\\\/risawave.org\\\/\",\"name\":\"risawave.org\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/risawave.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/risawave.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/risawave.org\\\/#organization\",\"name\":\"risawave.org\",\"url\":\"https:\\\/\\\/risawave.org\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/risawave.org\\\/de\\\/tag\\\/organisationswandel\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/risawave.org\\\/de\\\/tag\\\/organisationswandel\\\/#local-main-organization-logo\"},\"telephone\":[\"015140530884\"],\"openingHoursSpecification\":[],\"email\":\"office@newrella.hk\",\"faxNumber\":\"newrella Limited\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/risawave.org\\\/de\\\/tag\\\/organisationswandel\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/risawave.org\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Globales-logo-scaled-1.png\",\"contentUrl\":\"https:\\\/\\\/risawave.org\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Globales-logo-scaled-1.png\",\"width\":2560,\"height\":2560,\"caption\":\"risawave.org\"}]}<\/script>\n<meta name=\"geo.placename\" content=\"\u8202\u574e\u89d2\" \/>\n<meta name=\"geo.region\" content=\"Hong Kong\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"#Organisationswandel-Archiv - risawave.org","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/risawave.org\/de\/tag\/organisationswandel\/","og_locale":"de_DE","og_type":"article","og_title":"#Organisationswandel-Archiv","og_url":"https:\/\/risawave.org\/de\/tag\/organisationswandel\/","og_site_name":"risawave.org","og_image":[{"width":2560,"height":2560,"url":"https:\/\/risawave.org\/wp-content\/uploads\/2026\/01\/Globales-logo-scaled-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/risawave.org\/de\/tag\/organisationswandel\/","url":"https:\/\/risawave.org\/de\/tag\/organisationswandel\/","name":"#Organisationswandel-Archiv - risawave.org","isPartOf":{"@id":"https:\/\/risawave.org\/#website"},"breadcrumb":{"@id":"https:\/\/risawave.org\/de\/tag\/organisationswandel\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/risawave.org\/de\/tag\/organisationswandel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/risawave.org\/"},{"@type":"ListItem","position":2,"name":"#Organisationswandel"}]},{"@type":"WebSite","@id":"https:\/\/risawave.org\/#website","url":"https:\/\/risawave.org\/","name":"risawave.org","description":"","publisher":{"@id":"https:\/\/risawave.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/risawave.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Organization","Place"],"@id":"https:\/\/risawave.org\/#organization","name":"risawave.org","url":"https:\/\/risawave.org\/","logo":{"@id":"https:\/\/risawave.org\/de\/tag\/organisationswandel\/#local-main-organization-logo"},"image":{"@id":"https:\/\/risawave.org\/de\/tag\/organisationswandel\/#local-main-organization-logo"},"telephone":["015140530884"],"openingHoursSpecification":[],"email":"office@newrella.hk","faxNumber":"newrella Limited"},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/risawave.org\/de\/tag\/organisationswandel\/#local-main-organization-logo","url":"https:\/\/risawave.org\/wp-content\/uploads\/2026\/01\/Globales-logo-scaled-1.png","contentUrl":"https:\/\/risawave.org\/wp-content\/uploads\/2026\/01\/Globales-logo-scaled-1.png","width":2560,"height":2560,"caption":"risawave.org"}]},"geo.placename":"\u8202\u574e\u89d2","geo.region":"Hong Kong"},"_links":{"self":[{"href":"https:\/\/risawave.org\/de\/wp-json\/wp\/v2\/tags\/4539","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/risawave.org\/de\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/risawave.org\/de\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/risawave.org\/de\/wp-json\/wp\/v2\/posts?tags=4539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}